{"id":3040,"date":"2021-01-10T22:50:42","date_gmt":"2021-01-11T04:50:42","guid":{"rendered":"https:\/\/robertjsmithtx.com\/?post_type=tribe_events&#038;p=3040"},"modified":"2021-01-10T22:51:12","modified_gmt":"2021-01-11T04:51:12","slug":"work-session-36","status":"publish","type":"tribe_events","link":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/","title":{"rendered":"Bike and Trails Master Plan Review"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-3040","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bike and Trails Master Plan Review - Robert John Smith<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bike and Trails Master Plan Review - Robert John Smith\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/\" \/>\n<meta property=\"og:site_name\" content=\"Robert John Smith\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/robertjsmith24\" \/>\n<meta property=\"article:modified_time\" content=\"2021-01-11T04:51:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@robertjsmithtx\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/work-session-36\\\/\",\"url\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/work-session-36\\\/\",\"name\":\"Bike and Trails Master Plan Review - Robert John Smith\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/#website\"},\"datePublished\":\"2021-01-11T04:50:42+00:00\",\"dateModified\":\"2021-01-11T04:51:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/work-session-36\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/work-session-36\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/work-session-36\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/robertjsmithtx.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bike and Trails Master Plan Review\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/#website\",\"url\":\"https:\\\/\\\/robertjsmithtx.com\\\/\",\"name\":\"Robert John Smith\",\"description\":\"Former Garland City Council Member, District 8\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/robertjsmithtx.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bike and Trails Master Plan Review - Robert John Smith","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/","og_locale":"en_US","og_type":"article","og_title":"Bike and Trails Master Plan Review - Robert John Smith","og_url":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/","og_site_name":"Robert John Smith","article_publisher":"http:\/\/facebook.com\/robertjsmith24","article_modified_time":"2021-01-11T04:51:12+00:00","twitter_card":"summary_large_image","twitter_site":"@robertjsmithtx","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/","url":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/","name":"Bike and Trails Master Plan Review - Robert John Smith","isPartOf":{"@id":"https:\/\/robertjsmithtx.com\/#website"},"datePublished":"2021-01-11T04:50:42+00:00","dateModified":"2021-01-11T04:51:12+00:00","breadcrumb":{"@id":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/robertjsmithtx.com\/index.php\/event\/work-session-36\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robertjsmithtx.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/robertjsmithtx.com\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"Bike and Trails Master Plan Review"}]},{"@type":"WebSite","@id":"https:\/\/robertjsmithtx.com\/#website","url":"https:\/\/robertjsmithtx.com\/","name":"Robert John Smith","description":"Former Garland City Council Member, District 8","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robertjsmithtx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/3040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":2,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/3040\/revisions"}],"predecessor-version":[{"id":3042,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/3040\/revisions\/3042"}],"wp:attachment":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/media?parent=3040"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tags?post=3040"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=3040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}