{"id":2605,"date":"2019-11-04T20:11:18","date_gmt":"2019-11-05T02:11:18","guid":{"rendered":"http:\/\/robertjsmithtx.com\/?post_type=tribe_events&#038;p=2605"},"modified":"2019-11-04T20:11:18","modified_gmt":"2019-11-05T02:11:18","slug":"mlk-day-parade-2","status":"publish","type":"tribe_events","link":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/","title":{"rendered":"MLK Day Parade"},"content":{"rendered":"<p>MLK Day Parade<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MLK Day Parade<\/p>\n","protected":false},"author":1,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-2605","tribe_events","type-tribe_events","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MLK Day Parade - Robert John Smith<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MLK Day Parade - Robert John Smith\" \/>\n<meta property=\"og:description\" content=\"MLK Day Parade\" \/>\n<meta property=\"og:url\" content=\"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Robert John Smith\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/facebook.com\/robertjsmith24\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@robertjsmithtx\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/mlk-day-parade-2\\\/\",\"url\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/mlk-day-parade-2\\\/\",\"name\":\"MLK Day Parade - Robert John Smith\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/#website\"},\"datePublished\":\"2019-11-05T02:11:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/mlk-day-parade-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/mlk-day-parade-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/event\\\/mlk-day-parade-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/robertjsmithtx.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/robertjsmithtx.com\\\/index.php\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MLK Day Parade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/robertjsmithtx.com\\\/#website\",\"url\":\"https:\\\/\\\/robertjsmithtx.com\\\/\",\"name\":\"Robert John Smith\",\"description\":\"Former Garland City Council Member, District 8\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/robertjsmithtx.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MLK Day Parade - Robert John Smith","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/","og_locale":"en_US","og_type":"article","og_title":"MLK Day Parade - Robert John Smith","og_description":"MLK Day Parade","og_url":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/","og_site_name":"Robert John Smith","article_publisher":"http:\/\/facebook.com\/robertjsmith24","twitter_card":"summary_large_image","twitter_site":"@robertjsmithtx","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/","url":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/","name":"MLK Day Parade - Robert John Smith","isPartOf":{"@id":"https:\/\/robertjsmithtx.com\/#website"},"datePublished":"2019-11-05T02:11:18+00:00","breadcrumb":{"@id":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/robertjsmithtx.com\/index.php\/event\/mlk-day-parade-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/robertjsmithtx.com\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/robertjsmithtx.com\/index.php\/events\/"},{"@type":"ListItem","position":3,"name":"MLK Day Parade"}]},{"@type":"WebSite","@id":"https:\/\/robertjsmithtx.com\/#website","url":"https:\/\/robertjsmithtx.com\/","name":"Robert John Smith","description":"Former Garland City Council Member, District 8","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/robertjsmithtx.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/2605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/2605\/revisions"}],"predecessor-version":[{"id":2606,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events\/2605\/revisions\/2606"}],"wp:attachment":[{"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/media?parent=2605"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tags?post=2605"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/robertjsmithtx.com\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=2605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}